{"id":879,"date":"2021-09-21T14:36:32","date_gmt":"2021-09-21T14:36:32","guid":{"rendered":"https:\/\/delphoscentro.com\/?page_id=879"},"modified":"2022-05-15T08:48:36","modified_gmt":"2022-05-15T08:48:36","slug":"terapias","status":"publish","type":"page","link":"https:\/\/delphoscentro.com\/index.php\/terapias\/","title":{"rendered":"Terapias"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"879\" class=\"elementor elementor-879\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bu71rau elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bu71rau\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-p4b3n7m\" data-id=\"p4b3n7m\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-mudrmeq areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"mudrmeq\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/auriculoterapia-pdg3850s1dwdly9hg4oldpcpa6cm3am5yoswrgpn44.jpg\" title=\"auriculoterapia\" alt=\"auriculoterapia\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Auriculoterapia<\/a><\/h3><p class=\"elementor-image-box-description\">Auriculoterapia.\n\nTratamiento de enfermedades y patolog\u00edas a trav\u00e9s de la estimulaci\u00f3n de los puntos del pabell\u00f3n auricular. <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee81e23 areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"ee81e23\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/naturopatia-pdg38279gvsin4dkwlgpo82bi0qig7ayyaugbmttms.jpg\" title=\"naturopatia\" alt=\"naturopatia\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Naturopat\u00eda<\/a><\/h3><p class=\"elementor-image-box-description\">Conocimiento de plantas y alimentos para proporcionarnos una vida mucho m\u00e1s saludable. <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17bd216 areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"17bd216\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/reiki-1-pdg3850s1dwdly9hg4oldpcpa6cm3am5yoswrgpn44.jpg\" title=\"reiki\" alt=\"reiki\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Reiki<\/a><\/h3><p class=\"elementor-image-box-description\">Es un sistema de sanaci\u00f3n, autosanaci\u00f3n y de reequilibrio bioenerg\u00e9tico mediante la transmisi\u00f3n de energ\u00eda universal, a trav\u00e9s de la imposici\u00f3n de manos. act\u00faa directamente sobre el campo energ\u00e9tico del paciente corrigiendo los patrones de bloqueo. <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29d6e72 areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"29d6e72\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/2022\/05\/depositphotos_90238642-stock-photo-hand-performing-acupuncture-therapy-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Acupuntura<\/a><\/h3><p class=\"elementor-image-box-description\">Seg\u00fan la medicina tradicional china, esta t\u00e9cnica ancestral es utilizada para equilibrar el\nchi, la fuerza vital, que corre a trav\u00e9s de unos meridianos por todo nuestro cuerpo. Con\nla estimulaci\u00f3n de \u00e9stos en ciertos puntos exactos, conseguimos estimular nervios y\nm\u00fasculos para que mejoren el funcionamiento del organismo.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-94z8gp3\" data-id=\"94z8gp3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-o8y6vue areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"o8y6vue\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/grafologia-1-pdg3842xujv3acaulm9yt7l8osh8vlifmk5fa6r1ac.jpg\" title=\"grafologia\" alt=\"grafologia\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Grafolog\u00eda<\/a><\/h3><p class=\"elementor-image-box-description\">T\u00e9cnica que estudia las caracter\u00edsticas psicol\u00f3gicas de las personas a trav\u00e9s de la gorma y los rasgos de su escritura. A trav\u00e9s de ella podemos ayudarte a mejorar rasgos que pueden perjudicarte en tu d\u00eda a d\u00eda.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73gt1to areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"73gt1to\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/osteopatia-pdg38279gvsin4dkwlgpo82bi0qig7ayyaugbmttms.jpg\" title=\"osteopatia\" alt=\"osteopatia\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Osteopat\u00eda<\/a><\/h3><p class=\"elementor-image-box-description\">Es un enfoque asistencial diferente que parte de un sistema de diagn\u00f3stico para desarrollar un tratamiento especifico, ayudando a reequilibrar el organismo partiendo desde su estructura. es una terapia estrictamente manual que se complementa con la medicina alop\u00e1tica. <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-osow2h8 areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"osow2h8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/kinesologia-pdg3842xujv3acaulm9yt7l8osh8vlifmk5fa6r1ac.jpg\" title=\"kinesologia\" alt=\"kinesologia\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Shiatsu<\/a><\/h3><p class=\"elementor-image-box-description\">Pr\u00e1ctica de la medicina tradicional japonesa que consiste en presionar con los dedos en determinados meridianos reflejados en nuestro cuerpo para aliviar dolores, anestesiar determinas zonas y curar ciertas enfermedades.  <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8991dbb areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"8991dbb\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/2022\/05\/kisspng-kabbalah-tree-of-life-sefirot-judaism-symbol-5afd8a671cdc38.3572363015265654791182-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Sanaci\u00f3n por Yo Soy a trav\u00e9s de la Kabbalah.<\/a><\/h3><p class=\"elementor-image-box-description\">Desde la sabidur\u00eda cabal\u00edstica hasta las ense\u00f1anzas de Saint Germain, esta t\u00e9cnica\nenerg\u00e9tica ayudar\u00e1 a aliviar nuestros pesares f\u00edsicos y ps\u00edquicos adem\u00e1s de ofrecer una\nlimpieza \u00e1urica y energ\u00e9tica completa.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-phobwjz\" data-id=\"phobwjz\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-clyq47f areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"clyq47f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/shiatsu-pdg3850s1dwdly9hg4oldpcpa6cm3am5yoswrgpn44.jpg\" title=\"shiatsu\" alt=\"shiatsu\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Kinesiolog\u00eda<\/a><\/h3><p class=\"elementor-image-box-description\">La Kinsesiolog\u00eda es una terapia natural que eval\u00faa la respuesta de los m\u00fasculos para detectar desequilibrios en el organismo y, por tanto, prevenir trastornos o corregirlos, con el tratamiento m\u00e1s adecuado para el paciente. <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-mfva3rv areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"mfva3rv\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/reflexologia-pdg38353nptsyqc7r3vc8pts3elvnwepafhxswsfgk.jpg\" title=\"reflexologia\" alt=\"reflexologia\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Reflexolog\u00eda<\/a><\/h3><p class=\"elementor-image-box-description\">T\u00e9cnica oriental que trata las diferentes patolog\u00edas a trav\u00e9s de la presi\u00f3n ejercida en diferentes medianos repartidos por las zonas especificas a tratar.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8455f8f areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"8455f8f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/elementor\/thumbs\/terapia_floral-pdg38353nptsyqc7r3vc8pts3elvnwepafhxswsfgk.jpg\" title=\"terapia_floral\" alt=\"terapia_floral\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Terapia Floral<\/a><\/h3><p class=\"elementor-image-box-description\">Son preparados naturales, totalmente inocuos, con m\u00e1s de 70 a\u00f1os de historia a sus espaldas. El doctor. E. Bach descubri\u00f3 que act\u00faan a nivel vibracional y ayudan a reestablecer el equilibrio psiquico y energ\u00e9tico de la persona. <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-409c840 areas-box elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"409c840\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/2022\/05\/png-transparent-tarotology-psychic-reading-playing-card-astrology-others-magic-pisces-meditation-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Tarot<\/a><\/h3><p class=\"elementor-image-box-description\">Desde tiempos ancestrales el ser humano se ha interesado por su futuro, utilizando\nt\u00e9cnicas de todo tipo para poder contestar a las preguntas que como individuos\nracionales nos afectan. Mediante la t\u00e9cnica del tarot, ofrecemos la posibilidad de\ncontestar a esas preguntas a las que no tenemos respuesta.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2a26dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2a26dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8b89c3\" data-id=\"d8b89c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8444b19 elementor-widget elementor-widget-heading\" data-id=\"8444b19\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Adem\u00e1s ofrecemos los servicios de: Quiromasaje, masaje deportivo, nutrici\u00f3n, drenaje linf\u00e1tico, tratamiento miofascial, aromaterapia, fitoterapia, reeducaci\u00f3n postural, grafolog\u00eda infantil, yoga, meditaciones, crecimiento personal, kabbalah, sugarin, tratamientos galv\u00e1nicos, cosm\u00e9tica natural, cursos, seminarios, etc. <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4669df1 elementor-widget elementor-widget-heading\" data-id=\"4669df1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Si quieres m\u00e1s informaci\u00f3n sobre nuestras terapias escr\u00edbenos en este formulario y te informaros lo antes posible.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10895a3 elementor-widget elementor-widget-wpforms\" data-id=\"10895a3\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-711\"><form id=\"wpforms-form-711\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"711\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/879\" data-token=\"ddba13126659cd79bad183a5991da728\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-711-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-711-field_0\">Nombre <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-711-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-711-field_0\" class=\"wpforms-field-sublabel after \">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-711-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-711-field_0-last\" class=\"wpforms-field-sublabel after \">Apellidos<\/label><\/div><\/div><\/div><div id=\"wpforms-711-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-711-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-711-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-711-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-711-field_2\">Mensaje <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-711-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"711\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-711\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/delphoscentro.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Auriculoterapia Auriculoterapia. Tratamiento de enfermedades y patolog\u00edas a trav\u00e9s de la estimulaci\u00f3n de los puntos del pabell\u00f3n auricular. Naturopat\u00eda Conocimiento de plantas y alimentos para proporcionarnos una vida mucho m\u00e1s saludable. Reiki Es un sistema de sanaci\u00f3n, autosanaci\u00f3n y de reequilibrio bioenerg\u00e9tico mediante la transmisi\u00f3n de energ\u00eda universal, a trav\u00e9s de la imposici\u00f3n de manos. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-879","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Terapias - Delphos Centro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delphoscentro.com\/index.php\/terapias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terapias - Delphos Centro\" \/>\n<meta property=\"og:description\" content=\"Auriculoterapia Auriculoterapia. Tratamiento de enfermedades y patolog\u00edas a trav\u00e9s de la estimulaci\u00f3n de los puntos del pabell\u00f3n auricular. Naturopat\u00eda Conocimiento de plantas y alimentos para proporcionarnos una vida mucho m\u00e1s saludable. Reiki Es un sistema de sanaci\u00f3n, autosanaci\u00f3n y de reequilibrio bioenerg\u00e9tico mediante la transmisi\u00f3n de energ\u00eda universal, a trav\u00e9s de la imposici\u00f3n de manos. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delphoscentro.com\/index.php\/terapias\/\" \/>\n<meta property=\"og:site_name\" content=\"Delphos Centro\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-15T08:48:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/delphoscentro.com\/wp-content\/uploads\/2021\/09\/auriculoterapia-150x103.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/delphoscentro.com\/#website\",\"url\":\"https:\/\/delphoscentro.com\/\",\"name\":\"Delphos Centro\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/delphoscentro.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/delphoscentro.com\/index.php\/terapias\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/delphoscentro.com\/wp-content\/uploads\/2021\/09\/auriculoterapia.jpg\",\"contentUrl\":\"https:\/\/delphoscentro.com\/wp-content\/uploads\/2021\/09\/auriculoterapia.jpg\",\"width\":154,\"height\":103},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/delphoscentro.com\/index.php\/terapias\/#webpage\",\"url\":\"https:\/\/delphoscentro.com\/index.php\/terapias\/\",\"name\":\"Terapias - Delphos Centro\",\"isPartOf\":{\"@id\":\"https:\/\/delphoscentro.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/delphoscentro.com\/index.php\/terapias\/#primaryimage\"},\"datePublished\":\"2021-09-21T14:36:32+00:00\",\"dateModified\":\"2022-05-15T08:48:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/delphoscentro.com\/index.php\/terapias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/delphoscentro.com\/index.php\/terapias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/delphoscentro.com\/index.php\/terapias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/delphoscentro.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terapias\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terapias - Delphos Centro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delphoscentro.com\/index.php\/terapias\/","og_locale":"es_ES","og_type":"article","og_title":"Terapias - Delphos Centro","og_description":"Auriculoterapia Auriculoterapia. Tratamiento de enfermedades y patolog\u00edas a trav\u00e9s de la estimulaci\u00f3n de los puntos del pabell\u00f3n auricular. Naturopat\u00eda Conocimiento de plantas y alimentos para proporcionarnos una vida mucho m\u00e1s saludable. Reiki Es un sistema de sanaci\u00f3n, autosanaci\u00f3n y de reequilibrio bioenerg\u00e9tico mediante la transmisi\u00f3n de energ\u00eda universal, a trav\u00e9s de la imposici\u00f3n de manos. [&hellip;]","og_url":"https:\/\/delphoscentro.com\/index.php\/terapias\/","og_site_name":"Delphos Centro","article_modified_time":"2022-05-15T08:48:36+00:00","og_image":[{"url":"https:\/\/delphoscentro.com\/wp-content\/uploads\/2021\/09\/auriculoterapia-150x103.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/delphoscentro.com\/#website","url":"https:\/\/delphoscentro.com\/","name":"Delphos Centro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delphoscentro.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/delphoscentro.com\/index.php\/terapias\/#primaryimage","inLanguage":"es","url":"https:\/\/delphoscentro.com\/wp-content\/uploads\/2021\/09\/auriculoterapia.jpg","contentUrl":"https:\/\/delphoscentro.com\/wp-content\/uploads\/2021\/09\/auriculoterapia.jpg","width":154,"height":103},{"@type":"WebPage","@id":"https:\/\/delphoscentro.com\/index.php\/terapias\/#webpage","url":"https:\/\/delphoscentro.com\/index.php\/terapias\/","name":"Terapias - Delphos Centro","isPartOf":{"@id":"https:\/\/delphoscentro.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/delphoscentro.com\/index.php\/terapias\/#primaryimage"},"datePublished":"2021-09-21T14:36:32+00:00","dateModified":"2022-05-15T08:48:36+00:00","breadcrumb":{"@id":"https:\/\/delphoscentro.com\/index.php\/terapias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/delphoscentro.com\/index.php\/terapias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/delphoscentro.com\/index.php\/terapias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/delphoscentro.com\/"},{"@type":"ListItem","position":2,"name":"Terapias"}]}]}},"_links":{"self":[{"href":"https:\/\/delphoscentro.com\/index.php\/wp-json\/wp\/v2\/pages\/879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delphoscentro.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/delphoscentro.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/delphoscentro.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/delphoscentro.com\/index.php\/wp-json\/wp\/v2\/comments?post=879"}],"version-history":[{"count":13,"href":"https:\/\/delphoscentro.com\/index.php\/wp-json\/wp\/v2\/pages\/879\/revisions"}],"predecessor-version":[{"id":923,"href":"https:\/\/delphoscentro.com\/index.php\/wp-json\/wp\/v2\/pages\/879\/revisions\/923"}],"wp:attachment":[{"href":"https:\/\/delphoscentro.com\/index.php\/wp-json\/wp\/v2\/media?parent=879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}